{"id":157,"date":"2026-01-15T11:37:47","date_gmt":"2026-01-15T11:37:47","guid":{"rendered":"https:\/\/ffremodelacoes.pt\/?page_id=157"},"modified":"2026-03-03T15:45:24","modified_gmt":"2026-03-03T15:45:24","slug":"pedido-de-orcamento","status":"publish","type":"page","link":"https:\/\/ffremodelacoes.pt\/index.php\/pedido-de-orcamento\/","title":{"rendered":"Pedido de Or\u00e7amento"},"content":{"rendered":"\n<p>Preencha o formul\u00e1rio, para obter um pedido de or\u00e7amento, obtemos uma resposta ao seu formul\u00e1rio em 48 horas, se tiver alguma d\u00favida contacte-nos e tentaremos resolver o seu problema.<\/p>\n\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f243-o1\" lang=\"pt-PT\" dir=\"ltr\" data-wpcf7-id=\"243\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/157#wpcf7-f243-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"243\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_PT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f243-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-wrapper\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome completo\" value=\"\" type=\"text\" name=\"nome\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"email\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"codigo_postal\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"C\u00f3digo Postal\" value=\"\" type=\"text\" name=\"codigo_postal\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"servico\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"servico\"><option value=\"Selecione o servi\u00e7o\">Selecione o servi\u00e7o<\/option><option value=\"Tetos Falsos em Pladur\">Tetos Falsos em Pladur<\/option><option value=\"Capoto\">Capoto<\/option><option value=\"Remodela\u00e7\u00e3o Interior\">Remodela\u00e7\u00e3o Interior<\/option><option value=\"Remodela\u00e7\u00e3o Exterior\">Remodela\u00e7\u00e3o Exterior<\/option><\/select><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Pedir Or\u00e7amento\" \/>\n\t<\/p>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"189\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Preencha o formul\u00e1rio, para obter um pedido de or\u00e7amento, obtemos uma resposta ao seu formul\u00e1rio em 48 horas, se tiver alguma d\u00favida contacte-nos e tentaremos resolver o seu problema.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-157","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ffremodelacoes.pt\/index.php\/wp-json\/wp\/v2\/pages\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffremodelacoes.pt\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ffremodelacoes.pt\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ffremodelacoes.pt\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ffremodelacoes.pt\/index.php\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":26,"href":"https:\/\/ffremodelacoes.pt\/index.php\/wp-json\/wp\/v2\/pages\/157\/revisions"}],"predecessor-version":[{"id":247,"href":"https:\/\/ffremodelacoes.pt\/index.php\/wp-json\/wp\/v2\/pages\/157\/revisions\/247"}],"wp:attachment":[{"href":"https:\/\/ffremodelacoes.pt\/index.php\/wp-json\/wp\/v2\/media?parent=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}